{"id":4494,"date":"2025-04-29T13:06:24","date_gmt":"2025-04-29T20:06:24","guid":{"rendered":"https:\/\/www.archlegal.com\/discriminacion-por-genero\/"},"modified":"2026-03-11T04:30:29","modified_gmt":"2026-03-11T11:30:29","slug":"discriminacion-por-genero","status":"publish","type":"practice-areas","link":"https:\/\/www.archlegal.com\/es\/discriminacion-laboral\/discriminacion-por-genero\/","title":{"rendered":"Discriminaci\u00f3n por g\u00e9nero"},"content":{"rendered":"\n<section class=\"wp-block-custom-blocks-text-with-image text-with-image\"><div class=\"container\"><div class=\"text-with-image__row align--left\"><div class=\"column text-with-image__content\"><h2>Comprensi\u00f3n de la discriminaci\u00f3n de g\u00e9nero en el lugar de trabajo<\/h2>\n\n<p class=\"wp-block-paragraph\">Un hombre y una mujer en la misma empresa con las mismas cualificaciones y experiencia tienen salarios diferentes. \u00bfEs discriminaci\u00f3n de g\u00e9nero o discriminaci\u00f3n sexual? Posiblemente. La discriminaci\u00f3n de g\u00e9nero en el lugar de trabajo se produce cuando un empleado o solicitante de empleo recibe un trato injusto debido a su sexo, identidad de g\u00e9nero o expresi\u00f3n de g\u00e9nero. Esto puede incluir la desigualdad salarial por el mismo trabajo, pr\u00e1cticas de contrataci\u00f3n o promoci\u00f3n sesgadas, la exclusi\u00f3n de oportunidades, el acoso sexual o el sometimiento a diferentes est\u00e1ndares de rendimiento. Esta discriminaci\u00f3n no solo perjudica a las personas, sino que tambi\u00e9n socava la igualdad y la justicia en el lugar de trabajo.     <\/p>\n\n<a class=\"text-with-image__button btn__primary\" href=\"https:\/\/www.archlegal.com\/es\/contacto\/\">Solicitar una consulta gratuita<\/a><\/div><div class=\"column\"><div class=\"text-with-image__image decoration-align--left primary-image-shape\"><img decoding=\"async\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/Discrimination.jpg\" alt=\"\" width=\"1022\" height=\"660\"\/><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-group single-column-text block has-light-background-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Ley de Derechos Civiles de 1964 y protecciones de la Ley de Igualdad Salarial<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A nivel federal, el T\u00edtulo VII de la Ley de Derechos Civiles de 1964 y la Ley de Igualdad Salarial protegen a los trabajadores de la discriminaci\u00f3n laboral y por motivos de g\u00e9nero, garantizando la igualdad de trato en la contrataci\u00f3n, el salario y la promoci\u00f3n. Estas leyes son aplicadas por la Comisi\u00f3n para la Igualdad de Oportunidades en el Empleo (EEOC), que investiga y resuelve las denuncias en todo el pa\u00eds. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Protecciones de la Ley de Empleo y Vivienda Justos de California<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En California, los empleados se benefician de protecciones adicionales en virtud de la Ley de Empleo y Vivienda Justos (FEHA), la Ley de Derechos Civiles de Unruh y la Ley de Igualdad Salarial de California, todas las cuales ofrecen recursos s\u00f3lidos contra el sesgo en el lugar de trabajo, las pr\u00e1cticas discriminatorias y las represalias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un abogado experto en discriminaci\u00f3n de g\u00e9nero de ARCH Legal puede ayudar a los empleados a comprender sus derechos, reunir pruebas y emprender acciones legales cuando los empleadores infringen las leyes contra la discriminaci\u00f3n. Desde la presentaci\u00f3n de denuncias ante la EEOC o el Departamento de Derechos Civiles de California (CRD) hasta la presentaci\u00f3n de demandas, estos abogados especializados en discriminaci\u00f3n de g\u00e9nero luchan por garantizar la igualdad de trato, la igualdad salarial y la justicia en el lugar de trabajo para todos los g\u00e9neros. <\/p>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group two-columns-text is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group two-columns-text__row is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group column is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Leyes de California que protegen a los empleados de la discriminaci\u00f3n de g\u00e9nero<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">California ofrece algunas de las protecciones legales m\u00e1s s\u00f3lidas del pa\u00eds contra la discriminaci\u00f3n por motivos de g\u00e9nero a trav\u00e9s de la Ley de Empleo y Vivienda Justos. La FEHA proh\u00edbe a los empleadores discriminar a los empleados o solicitantes de empleo por motivos de g\u00e9nero, identidad de g\u00e9nero, expresi\u00f3n de g\u00e9nero u orientaci\u00f3n sexual. Esto incluye todos los aspectos del empleo:  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Contrataci\u00f3n<\/li>\n\n\n\n<li>Promociones<\/li>\n\n\n\n<li>Salario<\/li>\n\n\n\n<li>Formaci\u00f3n<\/li>\n\n\n\n<li>Despido<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La ley tambi\u00e9n proh\u00edbe el acoso y las represalias contra las personas que hacen valer sus derechos o participan en investigaciones en el lugar de trabajo. Los empleadores deben tomar medidas proactivas para prevenir el sesgo de g\u00e9nero, garantizar la denuncia de la discriminaci\u00f3n en el lugar de trabajo y mantener un entorno de trabajo inclusivo y respetuoso. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El g\u00e9nero no es una base para las disparidades salariales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la FEHA, la Ley de Igualdad Salarial de California garantiza que los hombres, las mujeres y los empleados no binarios reciban la misma remuneraci\u00f3n por un trabajo sustancialmente similar. Los empleadores no pueden justificar las disparidades salariales basadas en la discriminaci\u00f3n por motivos de g\u00e9nero o identidad de g\u00e9nero, a menos que las diferencias se basen en factores leg\u00edtimos como la antig\u00fcedad, el m\u00e9rito o la producci\u00f3n. La ley tambi\u00e9n proh\u00edbe las represalias contra los empleados que discuten o impugnan las desigualdades salariales, promoviendo la transparencia y la equidad salarial.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Los abogados especializados en discriminaci\u00f3n de g\u00e9nero protegen sus derechos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un abogado especializado en discriminaci\u00f3n de g\u00e9nero desempe\u00f1a un papel importante en la aplicaci\u00f3n de estos derechos. Ayudan a los empleados a reunir pruebas, presentar denuncias ante el Departamento de Derechos Civiles de California (CRD) y emprender acciones legales cuando sea necesario. Al responsabilizar a los empleadores en virtud de la ley estatal, estos abogados luchan por eliminar la desigualdad en el lugar de trabajo, garantizar una compensaci\u00f3n justa y promover un cambio sist\u00e9mico duradero que beneficie a todos los trabajadores de California.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group devider is-layout-flow wp-block-group-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-group column is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Signos comunes de discriminaci\u00f3n de g\u00e9nero en el lugar de trabajo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La discriminaci\u00f3n de g\u00e9nero puede adoptar muchas formas, algunas flagrantes, otras sutiles, pero todas violan las leyes laborales estatales y federales. Uno de los signos m\u00e1s claros de pr\u00e1cticas de contrataci\u00f3n discriminatorias es la desigualdad salarial para los empleados que realizan el mismo trabajo o un trabajo sustancialmente similar. Cuando los trabajadores de diferentes g\u00e9neros reciben una compensaci\u00f3n diferente a pesar de tener las mismas responsabilidades, habilidades y rendimiento, puede indicar una violaci\u00f3n de la Ley de Igualdad Salarial o de la Ley de Igualdad Salarial de California.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Denegaci\u00f3n de ascensos y oportunidades de promoci\u00f3n basadas en el g\u00e9nero<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Otro indicador com\u00fan es la denegaci\u00f3n de ascensos, formaci\u00f3n u oportunidades de promoci\u00f3n basadas en el g\u00e9nero o los estereotipos de g\u00e9nero. Los empleadores no pueden favorecer a un g\u00e9nero sobre otro para puestos de liderazgo, desarrollo profesional u oportunidades de carrera, ya que esto es una forma de discriminaci\u00f3n en el lugar de trabajo. Del mismo modo, los estereotipos, el acoso o las represalias contra los empleados que hacen valer sus derechos o denuncian prejuicios son ilegales en virtud de la Ley de Empleo y Vivienda Justos (FEHA) y el T\u00edtulo VII.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Despido improcedente por identidad o expresi\u00f3n de g\u00e9nero<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El despido improcedente o la degradaci\u00f3n relacionados con el g\u00e9nero, la identidad de g\u00e9nero o la expresi\u00f3n de g\u00e9nero son otra se\u00f1al de alerta. Los empleadores pueden intentar disfrazar el trato injusto y los motivos discriminatorios como problemas de rendimiento, pero los cambios repentinos despu\u00e9s de hacer valer los derechos o tomar una licencia protegida pueden revelar una intenci\u00f3n il\u00edcita. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hable con un abogado especializado en discriminaci\u00f3n de g\u00e9nero si observa se\u00f1ales de advertencia<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si observa estas se\u00f1ales de advertencia, es importante que consulte con un abogado laboralista o un abogado especializado en discriminaci\u00f3n de g\u00e9nero con experiencia. Un abogado con experiencia puede revisar su situaci\u00f3n, reunir pruebas y determinar si tiene una reclamaci\u00f3n viable. Le guiar\u00e1n en la presentaci\u00f3n de denuncias ante la EEOC o el Departamento de Derechos Civiles de California y luchar\u00e1n por proteger sus derechos, restaurar su carrera y obtener una compensaci\u00f3n justa.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group cta is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-cover\"><img decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-block-cover__image-background wp-image-2076 size-large\" alt=\"\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/74ab64aa3292c9dc8ca08e12a12e46446d58dfb4-3-1024x683.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/74ab64aa3292c9dc8ca08e12a12e46446d58dfb4-3-1024x683.jpg 1024w, https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/74ab64aa3292c9dc8ca08e12a12e46446d58dfb4-3-300x200.jpg 300w, https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/74ab64aa3292c9dc8ca08e12a12e46446d58dfb4-3-768x512.jpg 768w, https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/74ab64aa3292c9dc8ca08e12a12e46446d58dfb4-3.jpg 1254w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-90 has-background-dim wp-block-cover__gradient-background has-background-gradient has-hero-gradient-2-gradient-background\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group cta__content is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group cta__text is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Escuchamos atentamente a cada cliente<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">ARCH Legal adopta un enfoque personalizado y compasivo para cada caso de discriminaci\u00f3n. Desde su consulta inicial hasta la investigaci\u00f3n, la negociaci\u00f3n y, si es necesario, el juicio, estamos a su lado en cada paso del camino. Nuestra misi\u00f3n es simple: garantizar que su voz sea escuchada, que sus derechos est\u00e9n protegidos y que reciba la justicia y la compensaci\u00f3n que merece. Conf\u00ede en ARCH Legal para luchar por la igualdad y la rendici\u00f3n de cuentas.   <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group cta__buttons is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"btn__primary wp-block-paragraph\"><a href=\"https:\/\/www.archlegal.com\/es\/contacto\/\" data-type=\"link\" data-id=\"https:\/\/www.archlegal.com\/es\/contacto\/\">Cont\u00e1ctenos<\/a><\/p>\n\n\n\n<p class=\"cta__or wp-block-paragraph\">o<\/p>\n\n\n\n<div class=\"wp-block-group cta__phone-number is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/icon-phone-3.svg\" alt=\"\" class=\"wp-image-2088\"\/><\/figure>\n\n\n\n<p class=\"cta__phone wp-block-paragraph\"><a href=\"tel:+18663311338\">(866) 331-1338<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group single-column-text block has-white-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">C\u00f3mo probar la discriminaci\u00f3n de g\u00e9nero y presentar una reclamaci\u00f3n<\/h2>\n\n\n\n<div class=\"wp-block-group single-column-text__row is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00bfSospecha que el g\u00e9nero o la expresi\u00f3n de g\u00e9nero influyeron en que no recibiera un trabajo o un ascenso? Una cosa es sospechar de discriminaci\u00f3n; otra es probarla. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Es imprescindible contar con pruebas s\u00f3lidas de discriminaci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para probar con \u00e9xito la discriminaci\u00f3n de g\u00e9nero, se necesitan pruebas s\u00f3lidas y organizadas que demuestren que un empleador le trat\u00f3 de forma injusta debido a su g\u00e9nero, identidad de g\u00e9nero o expresi\u00f3n de g\u00e9nero. Los empleados deben reunir documentos clave, como registros salariales, evaluaciones de rendimiento, quejas internas y comunicaciones, incluidos correos electr\u00f3nicos o mensajes, que demuestren prejuicios o trato desigual. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las declaraciones de testigos de compa\u00f1eros de trabajo que observaron un comportamiento discriminatorio o represalias tambi\u00e9n pueden reforzar su caso. Es esencial mantener una cronolog\u00eda detallada de los incidentes: cu\u00e1ndo ocurrieron, qui\u00e9nes estuvieron involucrados y c\u00f3mo respondi\u00f3 la direcci\u00f3n. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Presentar una denuncia ante la EEOC o el CRD de California<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para emprender acciones formales, puede presentar una denuncia ante la Comisi\u00f3n para la Igualdad de Oportunidades en el Empleo (EEOC) en virtud del T\u00edtulo VII de la Ley de Derechos Civiles, o ante el Departamento de Derechos Civiles de California en virtud de la Ley de Empleo y Vivienda Justos. Por lo general, los empleados tienen entre 180 y 300 d\u00edas para presentar la denuncia ante la EEOC y tres a\u00f1os para presentarla ante el CRD, dependiendo de las circunstancias. Tras la investigaci\u00f3n, estos organismos pueden emitir una notificaci\u00f3n de \u00abDerecho a demandar\u00bb, que le permite presentar una demanda civil.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conf\u00ede en su abogado especializado en discriminaci\u00f3n de g\u00e9nero para presentar su caso<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un abogado experto en discriminaci\u00f3n de g\u00e9nero desempe\u00f1a un papel fundamental a la hora de guiarle a trav\u00e9s de este proceso. Le ayudan a recopilar pruebas, garantizar que se cumplen los plazos, negociar acuerdos y representarle ante los tribunales si es necesario. Con experiencia legal y defensa, su abogado puede ayudarle a obtener justicia, recuperar una indemnizaci\u00f3n y responsabilizar a su empleador por la discriminaci\u00f3n ilegal.  <\/p>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group single-column-text block has-light-background-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 elegir ARCH Legal para su caso de discriminaci\u00f3n de g\u00e9nero?<\/h2>\n\n\n\n<div class=\"wp-block-group single-column-text__row is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">ARCH Legal se compromete a luchar por la justicia y la igualdad en el lugar de trabajo. Nuestro equipo aporta una amplia experiencia y un profundo conocimiento de las leyes federales y de California sobre discriminaci\u00f3n de g\u00e9nero, incluido el T\u00edtulo VII de la Ley de Derechos Civiles, la Ley de Igualdad Salarial y la Ley de Empleo y Vivienda Justos de California. Nuestros abogados piensan de forma innovadora, sabiendo d\u00f3nde buscar en cada situaci\u00f3n posibles pruebas de discriminaci\u00f3n. Entendemos c\u00f3mo los empleadores intentan disfrazar los prejuicios y somos expertos en descubrir pruebas que demuestren el trato desigual y la discriminaci\u00f3n sist\u00e9mica.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00e1s de 300 millones de d\u00f3lares en indemnizaciones para nuestros clientes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro bufete tiene un historial probado de \u00e9xito en la representaci\u00f3n de empleados en casos relacionados con la desigualdad salarial, el acoso por motivos de g\u00e9nero, la denegaci\u00f3n de ascensos y el despido improcedente. Hemos ayudado a los clientes a recuperar m\u00e1s de 300 millones de d\u00f3lares en salarios perdidos y da\u00f1os por angustia emocional y a asegurar cambios significativos en sus lugares de trabajo. Tanto si su caso implica un sesgo sutil como una discriminaci\u00f3n flagrante, nuestros abogados est\u00e1n preparados para defender sus derechos con firmeza.  <\/p>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group alignfull faq is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group pattern-heading-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Preguntas frecuentes<\/h2>\n<\/div>\n\n\n<div class=\"accordions-structured-data__container\">\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfC\u00f3mo se demuestra la discriminaci\u00f3n de g\u00e9nero en el trabajo?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">Para demostrar la discriminaci\u00f3n de g\u00e9nero, debe demostrar que su empleador le trat\u00f3 de forma injusta debido a su g\u00e9nero. Las pruebas pueden incluir comentarios discriminatorios, diferencias en el salario o los ascensos, o ser objeto de medidas disciplinarias m\u00e1s severas que los empleados de otro g\u00e9nero. La documentaci\u00f3n, como correos electr\u00f3nicos, quejas de RR. HH., evaluaciones de rendimiento y declaraciones de testigos, es fundamental. Un patr\u00f3n de trato desigual o pr\u00e1cticas empresariales sesgadas tambi\u00e9n respaldan su caso. Es fundamental demostrar que estaba cualificado para su puesto y que sufri\u00f3 una acci\u00f3n adversa (como el despido o la degradaci\u00f3n) debido a su g\u00e9nero.    <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfCu\u00e1nto vale una demanda por discriminaci\u00f3n de g\u00e9nero?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">El valor de una demanda por discriminaci\u00f3n de g\u00e9nero depende de la gravedad del da\u00f1o, los salarios perdidos, la angustia emocional y la solidez de las pruebas. Los acuerdos pueden oscilar entre decenas de miles y varios cientos de miles de d\u00f3lares, y en algunos casos, m\u00e1s. La indemnizaci\u00f3n puede incluir el pago de salarios atrasados, la p\u00e9rdida de ingresos futuros, los da\u00f1os por angustia emocional y, en algunos casos, los da\u00f1os punitivos si el empleador actu\u00f3 con malicia. La ley federal establece l\u00edmites m\u00e1ximos para determinados da\u00f1os, pero algunas leyes estatales, como las de California, permiten una mayor recuperaci\u00f3n.   <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfNecesito un abogado para presentar una demanda por discriminaci\u00f3n?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">Aunque puede presentar una denuncia por discriminaci\u00f3n por su cuenta, contar con un abogado especializado en discriminaci\u00f3n de g\u00e9nero mejora enormemente sus posibilidades de \u00e9xito. Las leyes sobre discriminaci\u00f3n laboral son complejas y se aplican plazos estrictos para la presentaci\u00f3n de la denuncia. Un abogado puede evaluar su situaci\u00f3n, reunir pruebas, preparar la documentaci\u00f3n y representarle ante la EEOC o los organismos estatales como el Departamento de Derechos Civiles de California. Los abogados tambi\u00e9n ayudan a negociar acuerdos o a iniciar un litigio si es necesario. Sin asesoramiento legal, puede correr el riesgo de perderse pasos procesales cr\u00edticos o subestimar el valor de su reclamaci\u00f3n.    <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfQu\u00e9 debo hacer si sufro discriminaci\u00f3n de g\u00e9nero en el trabajo?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">Si sufre discriminaci\u00f3n de g\u00e9nero, documente todo: correos electr\u00f3nicos, incidentes, comentarios y nombres de testigos. Denuncie el problema a su departamento de RR. HH. o a su supervisor de acuerdo con la pol\u00edtica de la empresa. Si su empleador no act\u00faa o toma represalias, puede presentar una denuncia ante la EEOC o la agencia estatal de empleo justo. Evite renunciar antes de explorar las opciones legales, ya que puede afectar a su reclamaci\u00f3n. Conserve copias de todos los registros y comunicaciones.    <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfPuedo ser despedido por denunciar la discriminaci\u00f3n de g\u00e9nero?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">No. Las represalias contra un empleado por denunciar u oponerse a la discriminaci\u00f3n de g\u00e9nero son ilegales en virtud de las leyes federales y estatales, incluido el T\u00edtulo VII de la Ley de Derechos Civiles y la FEHA de California. Las actividades protegidas incluyen la presentaci\u00f3n de una denuncia, la participaci\u00f3n en una investigaci\u00f3n o el apoyo a la reclamaci\u00f3n de otro empleado. Las represalias pueden adoptar muchas formas: despido, degradaci\u00f3n, recortes salariales o exclusi\u00f3n de oportunidades. Para demostrar las represalias, debe demostrar que particip\u00f3 en una actividad protegida, sufri\u00f3 una acci\u00f3n adversa y que existe un v\u00ednculo entre ambas.    <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfLa discriminaci\u00f3n de g\u00e9nero se aplica tanto a los solicitantes de empleo como a los empleados?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">S\u00ed. Las leyes contra la discriminaci\u00f3n de g\u00e9nero protegen tanto a los empleados como a los solicitantes de empleo. Los empleadores no pueden basar la contrataci\u00f3n, las preguntas de la entrevista o las ofertas de empleo en el g\u00e9nero, la identidad de g\u00e9nero o la expresi\u00f3n de g\u00e9nero. Esto incluye el trato desigual en las ofertas salariales, los t\u00edtulos de los puestos o las oportunidades de promoci\u00f3n. La ley federal (T\u00edtulo VII) y las leyes estatales, como la FEHA de California, proh\u00edben los prejuicios durante la contrataci\u00f3n y la selecci\u00f3n. Incluso las pr\u00e1cticas sutiles, como preferir un g\u00e9nero para determinados puestos o rechazar a los solicitantes debido a estereotipos, pueden constituir discriminaci\u00f3n.    <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfQu\u00e9 da\u00f1os puedo recuperar en una demanda por discriminaci\u00f3n de g\u00e9nero?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">Las v\u00edctimas de discriminaci\u00f3n de g\u00e9nero pueden recuperar da\u00f1os econ\u00f3micos y no econ\u00f3micos, incluidos los salarios atrasados, los salarios futuros, la angustia emocional y las p\u00e9rdidas de su propio bolsillo. En los casos en que haya una conducta intencionada o maliciosa, los tribunales tambi\u00e9n pueden conceder da\u00f1os punitivos para castigar al empleador. Adem\u00e1s, los demandantes que ganan pueden recuperar los honorarios de los abogados y las costas judiciales. El valor de su reclamaci\u00f3n depende del alcance del da\u00f1o, la p\u00e9rdida de ingresos y la solidez de las pruebas. Las leyes federales y estatales, como el T\u00edtulo VII y la FEHA de California, rigen estas recuperaciones, aunque las leyes estatales pueden permitir una compensaci\u00f3n m\u00e1s amplia.    <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfPueden las demandas por discriminaci\u00f3n de g\u00e9nero solaparse con las demandas por acoso sexual?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">S\u00ed. La discriminaci\u00f3n de g\u00e9nero y el acoso sexual a menudo se solapan porque el acoso basado en el g\u00e9nero o la conducta sexual crea condiciones de trabajo desiguales. Por ejemplo, los comentarios no deseados, los avances o la hostilidad hacia un g\u00e9nero pueden calificarse como acoso y discriminaci\u00f3n. Un patr\u00f3n de este tipo de comportamiento tambi\u00e9n puede indicar una cultura m\u00e1s amplia de sesgo de g\u00e9nero. La presentaci\u00f3n de ambas reclamaciones puede reforzar su caso y aumentar las posibles soluciones.   <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfEst\u00e1n protegidos los empleados no binarios y transg\u00e9nero de la discriminaci\u00f3n de g\u00e9nero?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">S\u00ed. Las leyes federales y de California protegen a los empleados no binarios, transg\u00e9nero y de g\u00e9nero no conforme de la discriminaci\u00f3n. La decisi\u00f3n del Tribunal Supremo de los Estados Unidos en <em>Bostock contra el condado de Clayton<\/em> confirm\u00f3 que el T\u00edtulo VII proh\u00edbe la discriminaci\u00f3n basada en la identidad o expresi\u00f3n de g\u00e9nero. La FEHA de California va a\u00fan m\u00e1s lejos, protegiendo expl\u00edcitamente a las personas de los prejuicios debidos a la identidad de g\u00e9nero, la expresi\u00f3n de g\u00e9nero o el estado de transici\u00f3n. Los empleadores tambi\u00e9n deben respetar los nombres y pronombres preferidos y proporcionar un acceso adecuado a los ba\u00f1os.   <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-custom-blocks-accordion accordion\" data-include-schema=\"1\"><div class=\"accordion__row\"><div class=\"accordion__header\"><h3 class=\"accordion__header--heading\">\u00bfPuede un empleador preguntar sobre mi g\u00e9nero o estado civil durante una entrevista?<\/h3><span class=\"control-icon\"><\/span><\/div><div class=\"accordion__body\"><div class=\"accordion__content\">\n<p class=\"wp-block-paragraph\">Por lo general, no. Los empleadores no deben preguntar sobre su g\u00e9nero, estado civil o planes familiares durante las entrevistas, ya que estas preguntas pueden indicar prejuicios o intenci\u00f3n de discriminar. Las leyes federales y estatales, incluido el T\u00edtulo VII y la FEHA de California, proh\u00edben a los empleadores tomar decisiones de contrataci\u00f3n basadas en el g\u00e9nero o caracter\u00edsticas relacionadas. Las preguntas de la entrevista deben centrarse en las cualificaciones, las habilidades y los requisitos del puesto.   <\/p>\n<\/div><\/div><\/div><\/div>\n<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\/\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfC\u00f3mo se demuestra la discriminaci\u00f3n de g\u00e9nero en el trabajo?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Para demostrar la discriminaci\u00f3n de g\u00e9nero, debe demostrar que su empleador le trat\u00f3 de forma injusta debido a su g\u00e9nero. Las pruebas pueden incluir comentarios discriminatorios, diferencias en el salario o los ascensos, o ser objeto de medidas disciplinarias m\u00e1s severas que los empleados de otro g\u00e9nero. La documentaci\u00f3n, como correos electr\u00f3nicos, quejas de RR. HH., evaluaciones de rendimiento y declaraciones de testigos, es fundamental. Un patr\u00f3n de trato desigual o pr\u00e1cticas empresariales sesgadas tambi\u00e9n respaldan su caso. Es fundamental demostrar que estaba cualificado para su puesto y que sufri\u00f3 una acci\u00f3n adversa (como el despido o la degradaci\u00f3n) debido a su g\u00e9nero.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfCu\u00e1nto vale una demanda por discriminaci\u00f3n de g\u00e9nero?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"El valor de una demanda por discriminaci\u00f3n de g\u00e9nero depende de la gravedad del da\u00f1o, los salarios perdidos, la angustia emocional y la solidez de las pruebas. Los acuerdos pueden oscilar entre decenas de miles y varios cientos de miles de d\u00f3lares, y en algunos casos, m\u00e1s. La indemnizaci\u00f3n puede incluir el pago de salarios atrasados, la p\u00e9rdida de ingresos futuros, los da\u00f1os por angustia emocional y, en algunos casos, los da\u00f1os punitivos si el empleador actu\u00f3 con malicia. La ley federal establece l\u00edmites m\u00e1ximos para determinados da\u00f1os, pero algunas leyes estatales, como las de California, permiten una mayor recuperaci\u00f3n.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfNecesito un abogado para presentar una demanda por discriminaci\u00f3n?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Aunque puede presentar una denuncia por discriminaci\u00f3n por su cuenta, contar con un abogado especializado en discriminaci\u00f3n de g\u00e9nero mejora enormemente sus posibilidades de \u00e9xito. Las leyes sobre discriminaci\u00f3n laboral son complejas y se aplican plazos estrictos para la presentaci\u00f3n de la denuncia. Un abogado puede evaluar su situaci\u00f3n, reunir pruebas, preparar la documentaci\u00f3n y representarle ante la EEOC o los organismos estatales como el Departamento de Derechos Civiles de California. Los abogados tambi\u00e9n ayudan a negociar acuerdos o a iniciar un litigio si es necesario. Sin asesoramiento legal, puede correr el riesgo de perderse pasos procesales cr\u00edticos o subestimar el valor de su reclamaci\u00f3n.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfQu\u00e9 debo hacer si sufro discriminaci\u00f3n de g\u00e9nero en el trabajo?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Si sufre discriminaci\u00f3n de g\u00e9nero, documente todo: correos electr\u00f3nicos, incidentes, comentarios y nombres de testigos. Denuncie el problema a su departamento de RR. HH. o a su supervisor de acuerdo con la pol\u00edtica de la empresa. Si su empleador no act\u00faa o toma represalias, puede presentar una denuncia ante la EEOC o la agencia estatal de empleo justo. Evite renunciar antes de explorar las opciones legales, ya que puede afectar a su reclamaci\u00f3n. Conserve copias de todos los registros y comunicaciones.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfPuedo ser despedido por denunciar la discriminaci\u00f3n de g\u00e9nero?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"No. Las represalias contra un empleado por denunciar u oponerse a la discriminaci\u00f3n de g\u00e9nero son ilegales en virtud de las leyes federales y estatales, incluido el T\u00edtulo VII de la Ley de Derechos Civiles y la FEHA de California. Las actividades protegidas incluyen la presentaci\u00f3n de una denuncia, la participaci\u00f3n en una investigaci\u00f3n o el apoyo a la reclamaci\u00f3n de otro empleado. Las represalias pueden adoptar muchas formas: despido, degradaci\u00f3n, recortes salariales o exclusi\u00f3n de oportunidades. Para demostrar las represalias, debe demostrar que particip\u00f3 en una actividad protegida, sufri\u00f3 una acci\u00f3n adversa y que existe un v\u00ednculo entre ambas.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfLa discriminaci\u00f3n de g\u00e9nero se aplica tanto a los solicitantes de empleo como a los empleados?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"S\u00ed. Las leyes contra la discriminaci\u00f3n de g\u00e9nero protegen tanto a los empleados como a los solicitantes de empleo. Los empleadores no pueden basar la contrataci\u00f3n, las preguntas de la entrevista o las ofertas de empleo en el g\u00e9nero, la identidad de g\u00e9nero o la expresi\u00f3n de g\u00e9nero. Esto incluye el trato desigual en las ofertas salariales, los t\u00edtulos de los puestos o las oportunidades de promoci\u00f3n. La ley federal (T\u00edtulo VII) y las leyes estatales, como la FEHA de California, proh\u00edben los prejuicios durante la contrataci\u00f3n y la selecci\u00f3n. Incluso las pr\u00e1cticas sutiles, como preferir un g\u00e9nero para determinados puestos o rechazar a los solicitantes debido a estereotipos, pueden constituir discriminaci\u00f3n.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfQu\u00e9 da\u00f1os puedo recuperar en una demanda por discriminaci\u00f3n de g\u00e9nero?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Las v\u00edctimas de discriminaci\u00f3n de g\u00e9nero pueden recuperar da\u00f1os econ\u00f3micos y no econ\u00f3micos, incluidos los salarios atrasados, los salarios futuros, la angustia emocional y las p\u00e9rdidas de su propio bolsillo. En los casos en que haya una conducta intencionada o maliciosa, los tribunales tambi\u00e9n pueden conceder da\u00f1os punitivos para castigar al empleador. Adem\u00e1s, los demandantes que ganan pueden recuperar los honorarios de los abogados y las costas judiciales. El valor de su reclamaci\u00f3n depende del alcance del da\u00f1o, la p\u00e9rdida de ingresos y la solidez de las pruebas. Las leyes federales y estatales, como el T\u00edtulo VII y la FEHA de California, rigen estas recuperaciones, aunque las leyes estatales pueden permitir una compensaci\u00f3n m\u00e1s amplia.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfPueden las demandas por discriminaci\u00f3n de g\u00e9nero solaparse con las demandas por acoso sexual?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"S\u00ed. La discriminaci\u00f3n de g\u00e9nero y el acoso sexual a menudo se solapan porque el acoso basado en el g\u00e9nero o la conducta sexual crea condiciones de trabajo desiguales. Por ejemplo, los comentarios no deseados, los avances o la hostilidad hacia un g\u00e9nero pueden calificarse como acoso y discriminaci\u00f3n. Un patr\u00f3n de este tipo de comportamiento tambi\u00e9n puede indicar una cultura m\u00e1s amplia de sesgo de g\u00e9nero. La presentaci\u00f3n de ambas reclamaciones puede reforzar su caso y aumentar las posibles soluciones.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfEst\u00e1n protegidos los empleados no binarios y transg\u00e9nero de la discriminaci\u00f3n de g\u00e9nero?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"S\u00ed. Las leyes federales y de California protegen a los empleados no binarios, transg\u00e9nero y de g\u00e9nero no conforme de la discriminaci\u00f3n. La decisi\u00f3n del Tribunal Supremo de los Estados Unidos en Bostock contra el condado de Clayton confirm\u00f3 que el T\u00edtulo VII proh\u00edbe la discriminaci\u00f3n basada en la identidad o expresi\u00f3n de g\u00e9nero. La FEHA de California va a\u00fan m\u00e1s lejos, protegiendo expl\u00edcitamente a las personas de los prejuicios debidos a la identidad de g\u00e9nero, la expresi\u00f3n de g\u00e9nero o el estado de transici\u00f3n. Los empleadores tambi\u00e9n deben respetar los nombres y pronombres preferidos y proporcionar un acceso adecuado a los ba\u00f1os.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"\u00bfPuede un empleador preguntar sobre mi g\u00e9nero o estado civil durante una entrevista?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Por lo general, no. Los empleadores no deben preguntar sobre su g\u00e9nero, estado civil o planes familiares durante las entrevistas, ya que estas preguntas pueden indicar prejuicios o intenci\u00f3n de discriminar. Las leyes federales y estatales, incluido el T\u00edtulo VII y la FEHA de California, proh\u00edben a los empleadores tomar decisiones de contrataci\u00f3n basadas en el g\u00e9nero o caracter\u00edsticas relacionadas. Las preguntas de la entrevista deben centrarse en las cualificaciones, las habilidades y los requisitos del puesto.\"\n            }\n        }\n    ]\n}<\/script><\/div><\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group awards is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\">Nuestro reconocimiento<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/decorative.svg\" alt=\"\" class=\"wp-image-2112\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group awards__main is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"140\" height=\"116\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img1.webp\" alt=\"\" class=\"wp-image-2395\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"140\" height=\"116\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img2.webp\" alt=\"\" class=\"wp-image-2396\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"140\" height=\"116\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/hali-anderson.jpg\" alt=\"\" class=\"wp-image-2397\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"140\" height=\"116\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/hali-badge.jpg\" alt=\"\" class=\"wp-image-2398\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"122\" height=\"109\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img3.webp\" alt=\"\" class=\"wp-image-2399\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"166\" height=\"50\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img4.webp\" alt=\"\" class=\"wp-image-2400\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"104\" height=\"109\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img5.webp\" alt=\"\" class=\"wp-image-2401\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"193\" height=\"38\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img6.webp\" alt=\"\" class=\"wp-image-2402\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"96\" height=\"117\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img7.png\" alt=\"\" class=\"wp-image-2403\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"174\" height=\"71\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img8.png\" alt=\"\" class=\"wp-image-2404\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"109\" height=\"110\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/acknowledgement-img9.webp\" alt=\"\" class=\"wp-image-2405\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"140\" height=\"140\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/washington.webp\" alt=\"\" class=\"wp-image-2406\"\/><\/figure>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section id=\"contact-us\" class=\"wp-block-group contact-us has-light-background-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group contact-us__row is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group contact-us__column is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">\u00bfHa sufrido acoso o discriminaci\u00f3n en el lugar de trabajo?<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Encuentre al abogado adecuado para su caso<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00f3ngase en contacto con ARCH Legal hoy mismo para hablar con un abogado experto en derecho laboral dedicado a proteger sus derechos en el lugar de trabajo. Tanto si se enfrenta a discriminaci\u00f3n, represalias o infracciones salariales, nuestro equipo est\u00e1 preparado para ayudarle. Llame, env\u00ede un correo electr\u00f3nico o programe una consulta gratuita para hablar sobre su caso y explorar sus opciones legales.<\/p>\n\n\n\n<div class=\"wp-block-group contact-us__contact-details is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/icon-phone-4.svg\" alt=\"\" class=\"wp-image-2143\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"tel:+18663311338\">(866) 331-1338<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group contact-us__contact-details is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.archlegal.com\/wp-content\/uploads\/2025\/11\/location-1.svg\" alt=\"\" class=\"wp-image-2142\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/maps.app.goo.gl\/xXjb1axDADuXxYLC8\" data-type=\"link\" data-id=\"https:\/\/maps.app.goo.gl\/xXjb1axDADuXxYLC8\">3555 Fifth Avenue Suite 200,<br\/>\u2028San Diego, CA 92103<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group contact-us__column is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4098-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"4098\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/practice-areas\/4494#wpcf7-f4098-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4098\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4098-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-row\">\n   <label> Nombre <span class=\"wpcf7-form-control-wrap\" data-name=\"your-first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Introduzca su nombre\" value=\"\" type=\"text\" name=\"your-first-name\" \/><\/span><\/label><label> Apellido <span class=\"wpcf7-form-control-wrap\" data-name=\"your-last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Introduzca su apellido\" value=\"\" type=\"text\" name=\"your-last-name\" \/><\/span><\/label>\n<\/div>\n<div class=\"form-row\">\n   <label> N\u00famero de tel\u00e9fono <span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Introduzca su n\u00famero de tel\u00e9fono\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span> <\/label><label> Correo electr\u00f3nico <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Introduzca su direcci\u00f3n de correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label> \n<\/div>\n\n<div class=\"form-row\">\n  <label> Ciudad <span class=\"wpcf7-form-control-wrap\" data-name=\"your-city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Introduzca su ciudad\" value=\"\" type=\"text\" name=\"your-city\" \/><\/span> <\/label>\n  <label> Estado <span class=\"wpcf7-form-control-wrap\" data-name=\"your-state\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Introduzca su estado\" value=\"\" type=\"text\" name=\"your-state\" \/><\/span> <\/label>\n<\/div>\n\n<div class=\"form-row\">\n <label>  Necesito ayuda con: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"\u00bfC\u00f3mo podemos ayudarle?\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/div>\n\n<div class=\"form-row\">\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"consent\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"consent[]\" value=\"Acepto que contactar conmigo a trav\u00e9s de este formulario no constituye representaci\u00f3n legal ni crea una relaci\u00f3n abogado-cliente.\" \/><span class=\"wpcf7-list-item-label\">Acepto que contactar conmigo a trav\u00e9s de este formulario no constituye representaci\u00f3n legal ni crea una relaci\u00f3n abogado-cliente.<\/span><\/label><\/span><\/span><\/span>\n<\/div>\n\n<div class=\"form-row consent-row\">\n  <label><span class=\"wpcf7-form-control-wrap\" data-name=\"conditions\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"conditions\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> He le\u00eddo y acepto las <a href=\"\/es\/politica-de-privacidad\/\" target=\"_blank\">Pol\u00edticas de Privacidad<\/a>, \n  y <a href=\"\/es\/condiciones-de-uso\/\" target=\"_blank\">Condiciones de Uso<\/a>.<\/label>\n<\/div>\n\n<div class=\"wpcf7-turnstile cf-turnstile\" data-sitekey=\"0x4AAAAAACCGEsWJuOJVmetb\" data-response-field-name=\"_wpcf7_turnstile_response\"><\/div>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"enviar mensaje\" \/><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"39\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d16430.41740738804!2d-117.16569456052756!3d32.746116857276874!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x80d954c5befea6a5%3A0x80b7f10ad2154c37!2sARCH%20Legal%2C%20PC!5e0!3m2!1sen!2sdz!4v1762947744697!5m2!1sen!2sdz\" width=\"100%\" height=\"254\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\" title=\"Mapa de Arch Legal\"><\/iframe>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Ley de Derechos Civiles de 1964 y protecciones de la Ley de Igualdad Salarial A nivel federal, el T\u00edtulo VII de la Ley de Derechos Civiles de 1964 y la Ley de Igualdad Salarial protegen a los trabajadores de la discriminaci\u00f3n laboral y por motivos de g\u00e9nero, garantizando la igualdad de trato en la contrataci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4495,"parent":4580,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-4494","practice-areas","type-practice-areas","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/practice-areas\/4494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/practice-areas"}],"about":[{"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/types\/practice-areas"}],"author":[{"embeddable":true,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/comments?post=4494"}],"version-history":[{"count":6,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/practice-areas\/4494\/revisions"}],"predecessor-version":[{"id":6498,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/practice-areas\/4494\/revisions\/6498"}],"up":[{"embeddable":true,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/practice-areas\/4580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/media\/4495"}],"wp:attachment":[{"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/media?parent=4494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/categories?post=4494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archlegal.com\/es\/wp-json\/wp\/v2\/tags?post=4494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}